{"id":3122,"date":"2022-05-12T09:02:58","date_gmt":"2022-05-12T13:02:58","guid":{"rendered":"https:\/\/griswoldnursingrehab.com\/?p=3122"},"modified":"2022-05-12T09:02:59","modified_gmt":"2022-05-12T13:02:59","slug":"6-surgery-recovery-tips-for-the-senior-in-your-life","status":"publish","type":"post","link":"https:\/\/griswoldnursingrehab.com\/es\/blog\/6-consejos-de-recuperacion-de-cirugias-para-las-personas-mayores-en-su-vida\/","title":{"rendered":"6 consejos para la recuperaci\u00f3n de la cirug\u00eda para la persona mayor en su vida"},"content":{"rendered":"<p>La cirug\u00eda puede ser una perspectiva estresante para cualquier persona de cualquier edad. Sin embargo, cuando una persona mayor se somete a una intervenci\u00f3n quir\u00fargica, la recuperaci\u00f3n puede ser m\u00e1s compleja que la de una persona m\u00e1s joven debido a una serie de factores diferentes.<\/p>\n\n\n\n<p>Seg\u00fan&nbsp;<a href=\"https:\/\/caregiver.com\/articles\/preparing-seniors-surgery\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">El cuidador de hoy<\/a>En la mayor\u00eda de los casos, las personas mayores corren un mayor riesgo de sufrir complicaciones antes y despu\u00e9s de la cirug\u00eda. Las personas mayores suelen experimentar una curaci\u00f3n prolongada debido a la susceptibilidad a posibles infecciones, la falta de movilidad u otras complicaciones.&nbsp;<\/p>\n\n\n\n<p>Garantizar una recuperaci\u00f3n sin problemas despu\u00e9s de la cirug\u00eda es primordial para las personas mayores debido a estos mayores riesgos de posibles complicaciones de salud. Aqu\u00ed encontrar\u00e1 consejos \u00fatiles de planificaci\u00f3n que puede emplear para asegurarse de que su ser querido tenga una recuperaci\u00f3n lo m\u00e1s tranquila posible.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">1.   Preparar adecuadamente el hogar<\/h1>\n\n\n\n<p>Si su ser querido vuelve a casa despu\u00e9s de una intervenci\u00f3n quir\u00fargica, tome las medidas oportunas para asegurarse de que el hogar es seguro y todo es accesible.&nbsp;<\/p>\n\n\n\n<p>Esto incluye la retirada de cualquier alfombra o mesa auxiliar que pueda facilitar las ca\u00eddas o impedir el paso. Aseg\u00farate de que los mandos de la televisi\u00f3n, los libros, los tel\u00e9fonos y cualquier otro objeto que utilicen con frecuencia est\u00e9n al alcance de su mano.<\/p>\n\n\n\n<p>Si su ser querido vive en una casa en la que su dormitorio est\u00e1 en el segundo piso, considere la posibilidad de crear un dormitorio para \u00e9l en la planta baja para que no tenga que soportar un agotador viaje hacia arriba.&nbsp;<\/p>\n\n\n\n<p>Recuperarse de una intervenci\u00f3n quir\u00fargica ya es bastante dif\u00edcil, por lo que eliminar cualquier obst\u00e1culo en el frente dom\u00e9stico ayudar\u00e1 a que su ser querido se recupere de forma segura y c\u00f3moda.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">2.   Abast\u00e9zcase de alimentos nutritivos<\/h1>\n\n\n\n<p>Una dieta saludable puede contribuir en gran medida a la recuperaci\u00f3n de la cirug\u00eda. Asegurarse de que la cocina est\u00e1 provista de los alimentos adecuados o incluso de comidas precocinadas en el congelador puede ahorrarle mucho tiempo y molestias tras la operaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>El m\u00e9dico puede incluso pedir a su ser querido que siga una dieta espec\u00edfica tras la operaci\u00f3n, por lo que ser consciente de ello y hablarlo con su m\u00e9dico antes de la cirug\u00eda nunca es una mala idea. La preparaci\u00f3n lo es todo.&nbsp;<\/p>\n\n\n\n<p>Elaborar una lista de llamadas de emergencia y colocarla en un lugar accesible es tambi\u00e9n una precauci\u00f3n que puede tomar, ya que su ser querido puede necesitar asistencia inmediata en caso de ca\u00edda o complicaci\u00f3n m\u00e9dica.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">3.   Aseg\u00farese de tener a mano las herramientas adecuadas<\/h1>\n\n\n\n<p>Dependiendo del tipo de cirug\u00eda, su ser querido puede necesitar herramientas que usted no tiene normalmente y que debe adquirir.&nbsp;<\/p>\n\n\n\n<p>Hablar con su m\u00e9dico puede darle una mejor idea de los art\u00edculos personalizados que su ser querido necesitar\u00e1 para ayudar a garantizar una recuperaci\u00f3n c\u00f3moda de la cirug\u00eda.<\/p>\n\n\n\n<p>A continuaci\u00f3n encontrar\u00e1 una lista de art\u00edculos comunes que pueden necesitar las personas mayores:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Una silla de ruedas<\/li><li>Cama con marco ajustable&nbsp;<\/li><li>Calcetines de compresi\u00f3n<\/li><li>Tirantes para las piernas<\/li><li>Silla de ducha<\/li><li>Rieles en la ducha<\/li><li>Organizador de p\u00edldoras<\/li><li>Cintur\u00f3n de marcha<\/li><li>Caminante<\/li><li>Sistema de alerta m\u00e9dica<\/li><\/ul>\n\n\n\n<p>Estas herramientas y cualquier otra que pueda necesitar espec\u00edficamente pueden ser beneficiosas para el cuidado postoperatorio de un ser querido. Los diversos art\u00edculos enumerados pueden ayudar a prevenir ca\u00eddas, aumentar la accesibilidad y la movilidad y acelerar la recuperaci\u00f3n general.<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">4.   Est\u00e9 al tanto de todas las citas de seguimiento&nbsp;<\/h1>\n\n\n\n<p>Nunca est\u00e1 de m\u00e1s tener varios o\u00eddos presentes en las citas m\u00e9dicas. Aunque la memoria de su ser querido sea aguda, puede que no recuerde todas las noticias o instrucciones que se le proporcionen en un seguimiento.&nbsp;<\/p>\n\n\n\n<p>Si usted es el cuidador principal y quiere tener toda la informaci\u00f3n actualizada o la posibilidad de hacer preguntas cuando las tenga, entonces acompa\u00f1ar a su ser querido a la consulta de su m\u00e9dico est\u00e1 perfectamente bien.&nbsp;<\/p>\n\n\n\n<p>Incluso puede resultar beneficioso tomar notas en las citas de seguimiento para asegurarse de que no se salta nada, ni se omite ni se malinterpreta en el \u00e1mbito de las \u00f3rdenes del m\u00e9dico.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">5.   Si necesitas ayuda, p\u00eddela<\/h1>\n\n\n\n<p>Cuidar a un ser querido que se recupera de una operaci\u00f3n puede ser una tarea agotadora, e incluso puede ser algo que usted nunca haya manejado antes. Si le resulta dif\u00edcil manejar los cuidados postoperatorios, no hay que avergonzarse de contratar ayuda.&nbsp;<\/p>\n\n\n\n<p>Hay muchos&nbsp;<a href=\"https:\/\/dailycaring.com\/home-health-care-and-in-home-care-what-do-they-do\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">avenidas de salud en el hogar<\/a>&nbsp;que puedes explorar si te sientes abrumado, como una enfermera titulada o un ayudante de salud a domicilio.&nbsp;<\/p>\n\n\n\n<p>La contrataci\u00f3n de un cuidador a domicilio puede proporcionarle alivio y ofrecerle la tranquilidad de saber que su ser querido est\u00e1 al cuidado de un profesional de la salud.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">6.   Mantener la paciencia y la comprensi\u00f3n<\/h1>\n\n\n\n<p>Cuando un ser querido se est\u00e1 recuperando de una operaci\u00f3n, es posible que se retraiga, se deprima o se frustre con su situaci\u00f3n. Es importante que, cuando esto ocurra, tengas paciencia y comprensi\u00f3n, le apoyes en sus sentimientos y te abstengas de presionarle en un sentido u otro.&nbsp;<\/p>\n\n\n\n<p>Una recuperaci\u00f3n sin problemas s\u00f3lo tendr\u00e1 lugar si hay una discusi\u00f3n abierta, voluntad de escuchar y un compromiso de apoyo con un ser querido que puede estar confundido o frustrado con su situaci\u00f3n de recuperaci\u00f3n.&nbsp;<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">C\u00f3mo puede ayudar Griswold Rehabilitation and Health Care<\/h1>\n\n\n\n<p>El personal de Griswold Rehabilitation and Health Care se dedica a levantar el \u00e1nimo y a fomentar un estilo de vida saludable y feliz para todos nuestros residentes.&nbsp;<\/p>\n\n\n\n<p>Nuestra comunidad proporciona cuidados de larga duraci\u00f3n y rehabilitaci\u00f3n entre nuestros distintos niveles de atenci\u00f3n. Ofrecemos programas de terapia ocupacional y actividades que est\u00e1n dise\u00f1ados para fomentar el compromiso para garantizar una recuperaci\u00f3n c\u00f3moda y gratificante.&nbsp;<\/p>\n\n\n\n<p>Estamos aqu\u00ed para ofrecerle asistencia, responder a sus preguntas y guiarle en el proceso de la vida de los mayores. Si desea programar una&nbsp;<a href=\"https:\/\/griswoldnursingrehab.com\/es\/contacte-con-nosotros-2\/\">consulta gratuita<\/a>Nos encantar\u00eda ayudarle en todo lo que podamos.&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La cirug\u00eda puede ser una perspectiva estresante para cualquier persona de cualquier edad. Sin embargo, cuando una persona mayor se somete a una operaci\u00f3n, la recuperaci\u00f3n puede...<\/p>","protected":false},"author":2,"featured_media":3123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[8],"tags":[24,29,30,26,27,28],"class_list":["post-3122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-skilled-nursing","tag-rehabilitation","tag-senior-care","tag-senior-living","tag-surgerey","tag-surgery","tag-surgery-recovery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6\u00a0Surgery Recovery Tips\u00a0for the Senior in Your Life | Griswold Assisted Living &amp; Rehabilitation<\/title>\n<meta name=\"description\" content=\"Blog explaining ways in which seniors can best recover after surgery and how Griswold Rehabilitation and Healthcare can help.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/griswoldnursingrehab.com\/es\/blog\/6-consejos-de-recuperacion-de-cirugias-para-las-personas-mayores-en-su-vida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6\u00a0Surgery Recovery Tips\u00a0for the Senior in Your Life\" \/>\n<meta property=\"og:description\" content=\"Blog explaining ways in which seniors can best recover after surgery and how Griswold Rehabilitation and Healthcare can help.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/griswoldnursingrehab.com\/es\/blog\/6-consejos-de-recuperacion-de-cirugias-para-las-personas-mayores-en-su-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Griswold Rehabilitation &amp; Health Care Center\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T13:02:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T13:02:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2022\/05\/TUT_bigstock-Caring-nurse-helps-elderly-wom-222592411.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"slproduction@grapevinedesigns.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"slproduction@grapevinedesigns.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 consejos para la recuperaci\u00f3n de la cirug\u00eda para la persona mayor en su vida | Griswold Assisted Living &amp; Rehabilitation","description":"Blog en el que se explican las formas en las que las personas mayores pueden recuperarse mejor despu\u00e9s de la cirug\u00eda y c\u00f3mo Griswold Rehabilitaci\u00f3n y Salud puede ayudar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/griswoldnursingrehab.com\/es\/blog\/6-consejos-de-recuperacion-de-cirugias-para-las-personas-mayores-en-su-vida\/","og_locale":"es_ES","og_type":"article","og_title":"6\u00a0Surgery Recovery Tips\u00a0for the Senior in Your Life","og_description":"Blog explaining ways in which seniors can best recover after surgery and how Griswold Rehabilitation and Healthcare can help.","og_url":"https:\/\/griswoldnursingrehab.com\/es\/blog\/6-consejos-de-recuperacion-de-cirugias-para-las-personas-mayores-en-su-vida\/","og_site_name":"Griswold Rehabilitation &amp; Health Care Center","article_published_time":"2022-05-12T13:02:58+00:00","article_modified_time":"2022-05-12T13:02:59+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2022\/05\/TUT_bigstock-Caring-nurse-helps-elderly-wom-222592411.jpg","type":"image\/jpeg"}],"author":"slproduction@grapevinedesigns.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"slproduction@grapevinedesigns.com","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#article","isPartOf":{"@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/"},"author":{"name":"slproduction@grapevinedesigns.com","@id":"https:\/\/griswoldnursingrehab.com\/#\/schema\/person\/f3d9b6090e41b65affeaba9ba14b41c7"},"headline":"6\u00a0Surgery Recovery Tips\u00a0for the Senior in Your Life","datePublished":"2022-05-12T13:02:58+00:00","dateModified":"2022-05-12T13:02:59+00:00","mainEntityOfPage":{"@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/"},"wordCount":955,"commentCount":0,"publisher":{"@id":"https:\/\/griswoldnursingrehab.com\/#organization"},"image":{"@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#primaryimage"},"thumbnailUrl":"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2022\/05\/TUT_bigstock-Caring-nurse-helps-elderly-wom-222592411.jpg","keywords":["rehabilitation","senior care","senior living","surgerey","surgery","surgery recovery"],"articleSection":["Skilled Nursing"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#respond"]}]},{"@type":["WebPage","MedicalWebPage"],"@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/","url":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/","name":"6 consejos para la recuperaci\u00f3n de la cirug\u00eda para la persona mayor en su vida | Griswold Assisted Living &amp; Rehabilitation","isPartOf":{"@id":"https:\/\/griswoldnursingrehab.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#primaryimage"},"image":{"@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#primaryimage"},"thumbnailUrl":"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2022\/05\/TUT_bigstock-Caring-nurse-helps-elderly-wom-222592411.jpg","datePublished":"2022-05-12T13:02:58+00:00","dateModified":"2022-05-12T13:02:59+00:00","description":"Blog en el que se explican las formas en las que las personas mayores pueden recuperarse mejor despu\u00e9s de la cirug\u00eda y c\u00f3mo Griswold Rehabilitaci\u00f3n y Salud puede ayudar.","breadcrumb":{"@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#primaryimage","url":"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2022\/05\/TUT_bigstock-Caring-nurse-helps-elderly-wom-222592411.jpg","contentUrl":"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2022\/05\/TUT_bigstock-Caring-nurse-helps-elderly-wom-222592411.jpg","width":900,"height":600,"caption":"Female nurse helps senior woman out of bed"},{"@type":"BreadcrumbList","@id":"https:\/\/griswoldnursingrehab.com\/blog\/6-surgery-recovery-tips-for-the-senior-in-your-life\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/griswoldnursingrehab.com\/"},{"@type":"ListItem","position":2,"name":"6\u00a0Surgery Recovery Tips\u00a0for the Senior in Your Life"}]},{"@type":"WebSite","@id":"https:\/\/griswoldnursingrehab.com\/#website","url":"https:\/\/griswoldnursingrehab.com\/","name":"Centro de Rehabilitaci\u00f3n y Cuidado de la Salud Griswold","description":"A Tutera Rehabilitation &amp; Health Care Center Assisted Living Community","publisher":{"@id":"https:\/\/griswoldnursingrehab.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/griswoldnursingrehab.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/griswoldnursingrehab.com\/#organization","name":"Griswold Assisted Living, Rehabilitation & Health Care Center","url":"https:\/\/griswoldnursingrehab.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/griswoldnursingrehab.com\/#\/schema\/logo\/image\/","url":"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2021\/10\/Griswold-logo-lg.png","contentUrl":"https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2021\/10\/Griswold-logo-lg.png","width":400,"height":84,"caption":"Griswold Assisted Living, Rehabilitation & Health Care Center"},"image":{"@id":"https:\/\/griswoldnursingrehab.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/griswoldnursingrehab.com\/#\/schema\/person\/f3d9b6090e41b65affeaba9ba14b41c7","name":"slproduction@grapevinedesigns.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8cc804516f0d13fd78e7d52684dfb8d3a7ac81fdd0ca7c7ac6538a8346b9f096?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8cc804516f0d13fd78e7d52684dfb8d3a7ac81fdd0ca7c7ac6538a8346b9f096?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8cc804516f0d13fd78e7d52684dfb8d3a7ac81fdd0ca7c7ac6538a8346b9f096?s=96&d=mm&r=g","caption":"slproduction@grapevinedesigns.com"},"url":"https:\/\/griswoldnursingrehab.com\/es\/blog\/author\/slproductiongrapevinedesigns-com\/"}]}},"taxonomy_info":{"category":[{"value":8,"label":"Skilled Nursing"}],"post_tag":[{"value":24,"label":"rehabilitation"},{"value":29,"label":"senior care"},{"value":30,"label":"senior living"},{"value":26,"label":"surgerey"},{"value":27,"label":"surgery"},{"value":28,"label":"surgery recovery"}]},"featured_image_src_large":["https:\/\/griswoldnursingrehab.com\/wp-content\/uploads\/2022\/05\/TUT_bigstock-Caring-nurse-helps-elderly-wom-222592411.jpg",900,600,false],"author_info":{"display_name":"slproduction@grapevinedesigns.com","author_link":"https:\/\/griswoldnursingrehab.com\/es\/blog\/author\/slproductiongrapevinedesigns-com\/"},"comment_info":111,"category_info":[{"term_id":8,"name":"Skilled Nursing","slug":"skilled-nursing","term_group":0,"term_taxonomy_id":8,"taxonomy":"category","description":"","parent":0,"count":3,"filter":"raw","cat_ID":8,"category_count":3,"category_description":"","cat_name":"Skilled Nursing","category_nicename":"skilled-nursing","category_parent":0}],"tag_info":[{"term_id":24,"name":"rehabilitation","slug":"rehabilitation","term_group":0,"term_taxonomy_id":24,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"},{"term_id":29,"name":"senior care","slug":"senior-care","term_group":0,"term_taxonomy_id":29,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw"},{"term_id":30,"name":"senior living","slug":"senior-living","term_group":0,"term_taxonomy_id":30,"taxonomy":"post_tag","description":"","parent":0,"count":4,"filter":"raw"},{"term_id":26,"name":"surgerey","slug":"surgerey","term_group":0,"term_taxonomy_id":26,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":27,"name":"surgery","slug":"surgery","term_group":0,"term_taxonomy_id":27,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":28,"name":"surgery recovery","slug":"surgery-recovery","term_group":0,"term_taxonomy_id":28,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/posts\/3122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/comments?post=3122"}],"version-history":[{"count":0,"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/posts\/3122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/media\/3123"}],"wp:attachment":[{"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/media?parent=3122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/categories?post=3122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/griswoldnursingrehab.com\/es\/wp-json\/wp\/v2\/tags?post=3122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}